{"id":212302,"date":"2022-04-01T14:08:30","date_gmt":"2022-04-01T17:08:30","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/"},"modified":"2022-04-01T14:08:30","modified_gmt":"2022-04-01T17:08:30","slug":"hospedeiro-o-que-e","status":"publish","type":"dicio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/","title":{"rendered":"Hospedeiro &#8211; O que \u00e9"},"content":{"rendered":"<p>Chama-se ao ser humano ou animal que acolhe bact\u00e9rias, v\u00edrus ou parasitas.<\/p>\n<p>Chama-se hospedeiro prim\u00e1rio aquele onde se desenvolve a maior parte da sua exist\u00eancia e, sobretudo, o seu crescimento. Por outro lado, \u00e9 chamado de hospedeiro secund\u00e1rio ao que abriga o parasita apenas numa fase inicial do seu crescimento.<\/p>\n","protected":false},"template":"","class_list":["post-212302","dicio","type-dicio","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hospedeiro - O que \u00e9 - Consult\u00f3rios e Cl\u00ednicas<\/title>\n<meta name=\"description\" content=\"Hospedeiro - O que \u00e9 . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospedeiro - O que \u00e9\" \/>\n<meta property=\"og:description\" content=\"Hospedeiro - O que \u00e9 . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/hospedeiro-o-que-e\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/hospedeiro-o-que-e\\\/\",\"name\":\"Hospedeiro - O que \u00e9 - Consult\u00f3rios e Cl\u00ednicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2022-04-01T17:08:30+00:00\",\"description\":\"Hospedeiro - O que \u00e9 . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/hospedeiro-o-que-e\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/hospedeiro-o-que-e\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/hospedeiro-o-que-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Base de Dados\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hospedeiro &#8211; O que \u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hospedeiro - O que \u00e9 - Consult\u00f3rios e Cl\u00ednicas","description":"Hospedeiro - O que \u00e9 . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospedeiro - O que \u00e9","og_description":"Hospedeiro - O que \u00e9 . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/","name":"Hospedeiro - O que \u00e9 - Consult\u00f3rios e Cl\u00ednicas","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2022-04-01T17:08:30+00:00","description":"Hospedeiro - O que \u00e9 . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/hospedeiro-o-que-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Base de Dados","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/"},{"@type":"ListItem","position":3,"name":"Hospedeiro &#8211; O que \u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio\/212302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/dicio"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=212302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}