{"id":213465,"date":"2022-12-07T02:06:01","date_gmt":"2022-12-07T05:06:01","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/"},"modified":"2022-12-07T02:06:01","modified_gmt":"2022-12-07T05:06:01","slug":"diabetico-pode-beber-bebida-alcoolica","status":"publish","type":"dicio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/","title":{"rendered":"Diab\u00e9tico pode beber bebida alco\u00f3lica?"},"content":{"rendered":"<p>Sim, pessoas com diabetes podem beber bebida alco\u00f3lica, desde que seja com modera\u00e7\u00e3o e com muito aten\u00e7\u00e3o para que n\u00e3o se aumente o risco de hipoglicemia (diminui\u00e7\u00e3o do a\u00e7\u00facar no sangue).<\/p>\n","protected":false},"template":"","class_list":["post-213465","dicio","type-dicio","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Diab\u00e9tico pode beber bebida alco\u00f3lica? - Consult\u00f3rios e Cl\u00ednicas<\/title>\n<meta name=\"description\" content=\"Diab\u00e9tico pode beber bebida alco\u00f3lica? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diab\u00e9tico pode beber bebida alco\u00f3lica?\" \/>\n<meta property=\"og:description\" content=\"Diab\u00e9tico pode beber bebida alco\u00f3lica? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/diabetico-pode-beber-bebida-alcoolica\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/diabetico-pode-beber-bebida-alcoolica\\\/\",\"name\":\"Diab\u00e9tico pode beber bebida alco\u00f3lica? - Consult\u00f3rios e Cl\u00ednicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2022-12-07T05:06:01+00:00\",\"description\":\"Diab\u00e9tico pode beber bebida alco\u00f3lica? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/diabetico-pode-beber-bebida-alcoolica\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/diabetico-pode-beber-bebida-alcoolica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/diabetico-pode-beber-bebida-alcoolica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Base de Dados\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diab\u00e9tico pode beber bebida alco\u00f3lica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diab\u00e9tico pode beber bebida alco\u00f3lica? - Consult\u00f3rios e Cl\u00ednicas","description":"Diab\u00e9tico pode beber bebida alco\u00f3lica? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/","og_locale":"pt_BR","og_type":"article","og_title":"Diab\u00e9tico pode beber bebida alco\u00f3lica?","og_description":"Diab\u00e9tico pode beber bebida alco\u00f3lica? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/","name":"Diab\u00e9tico pode beber bebida alco\u00f3lica? - Consult\u00f3rios e Cl\u00ednicas","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2022-12-07T05:06:01+00:00","description":"Diab\u00e9tico pode beber bebida alco\u00f3lica? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/diabetico-pode-beber-bebida-alcoolica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Base de Dados","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/"},{"@type":"ListItem","position":3,"name":"Diab\u00e9tico pode beber bebida alco\u00f3lica?"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio\/213465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/dicio"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=213465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}