{"id":213850,"date":"2021-04-23T20:08:28","date_gmt":"2021-04-23T23:08:28","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/"},"modified":"2021-04-23T20:08:28","modified_gmt":"2021-04-23T23:08:28","slug":"prednisona-engorda-quais-os-efeitos-colaterais","status":"publish","type":"dicio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/","title":{"rendered":"Prednisona engorda? Quais os efeitos colaterais?"},"content":{"rendered":"<p>Prednisona pode engordar devido \u00e0 reten\u00e7\u00e3o de l\u00edquidos e sal. Al\u00e9m disso, por ser tratar de um corticoide, a prednisona pode aumentar o apetite, o que contribui ainda mais para o ganho de peso. O incha\u00e7o ocorre pela reten\u00e7\u00e3o de s\u00f3dio, que provoca a reten\u00e7\u00e3o de \u00e1gua no corpo.<\/p>\n","protected":false},"template":"","class_list":["post-213850","dicio","type-dicio","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prednisona engorda? Quais os efeitos colaterais? - Consult\u00f3rios e Cl\u00ednicas<\/title>\n<meta name=\"description\" content=\"Prednisona engorda? Quais os efeitos colaterais? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prednisona engorda? Quais os efeitos colaterais?\" \/>\n<meta property=\"og:description\" content=\"Prednisona engorda? Quais os efeitos colaterais? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/prednisona-engorda-quais-os-efeitos-colaterais\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/prednisona-engorda-quais-os-efeitos-colaterais\\\/\",\"name\":\"Prednisona engorda? Quais os efeitos colaterais? - Consult\u00f3rios e Cl\u00ednicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2021-04-23T23:08:28+00:00\",\"description\":\"Prednisona engorda? Quais os efeitos colaterais? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/prednisona-engorda-quais-os-efeitos-colaterais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/prednisona-engorda-quais-os-efeitos-colaterais\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/prednisona-engorda-quais-os-efeitos-colaterais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Base de Dados\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prednisona engorda? Quais os efeitos colaterais?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prednisona engorda? Quais os efeitos colaterais? - Consult\u00f3rios e Cl\u00ednicas","description":"Prednisona engorda? Quais os efeitos colaterais? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/","og_locale":"pt_BR","og_type":"article","og_title":"Prednisona engorda? Quais os efeitos colaterais?","og_description":"Prednisona engorda? Quais os efeitos colaterais? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/","name":"Prednisona engorda? Quais os efeitos colaterais? - Consult\u00f3rios e Cl\u00ednicas","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2021-04-23T23:08:28+00:00","description":"Prednisona engorda? Quais os efeitos colaterais? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/prednisona-engorda-quais-os-efeitos-colaterais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Base de Dados","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/"},{"@type":"ListItem","position":3,"name":"Prednisona engorda? Quais os efeitos colaterais?"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio\/213850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/dicio"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=213850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}