{"id":214398,"date":"2022-10-14T11:01:12","date_gmt":"2022-10-14T14:01:12","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/"},"modified":"2022-10-14T11:01:12","modified_gmt":"2022-10-14T14:01:12","slug":"quando-devo-tomar-soro-caseiro","status":"publish","type":"dicio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/","title":{"rendered":"Quando devo tomar soro caseiro?"},"content":{"rendered":"<p>O soro caseiro deve ser tomado em casos de diarreia e v\u00f4mitos, para prevenir a desidrata\u00e7\u00e3o. Apesar de n\u00e3o cortar a diarreia, o soro caseiro rep\u00f5e o l\u00edquido e os sais minerais eliminados nas fezes ou v\u00f4mitos.<\/p>\n","protected":false},"template":"","class_list":["post-214398","dicio","type-dicio","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quando devo tomar soro caseiro? - Consult\u00f3rios e Cl\u00ednicas<\/title>\n<meta name=\"description\" content=\"Quando devo tomar soro caseiro? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando devo tomar soro caseiro?\" \/>\n<meta property=\"og:description\" content=\"Quando devo tomar soro caseiro? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/quando-devo-tomar-soro-caseiro\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/quando-devo-tomar-soro-caseiro\\\/\",\"name\":\"Quando devo tomar soro caseiro? - Consult\u00f3rios e Cl\u00ednicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2022-10-14T14:01:12+00:00\",\"description\":\"Quando devo tomar soro caseiro? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/quando-devo-tomar-soro-caseiro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/quando-devo-tomar-soro-caseiro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/quando-devo-tomar-soro-caseiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Base de Dados\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quando devo tomar soro caseiro?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quando devo tomar soro caseiro? - Consult\u00f3rios e Cl\u00ednicas","description":"Quando devo tomar soro caseiro? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/","og_locale":"pt_BR","og_type":"article","og_title":"Quando devo tomar soro caseiro?","og_description":"Quando devo tomar soro caseiro? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/","name":"Quando devo tomar soro caseiro? - Consult\u00f3rios e Cl\u00ednicas","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2022-10-14T14:01:12+00:00","description":"Quando devo tomar soro caseiro? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/quando-devo-tomar-soro-caseiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Base de Dados","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/"},{"@type":"ListItem","position":3,"name":"Quando devo tomar soro caseiro?"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio\/214398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/dicio"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=214398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}