{"id":216197,"date":"2021-05-24T12:23:49","date_gmt":"2021-05-24T15:23:49","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/"},"modified":"2021-05-24T12:23:49","modified_gmt":"2021-05-24T15:23:49","slug":"qual-a-diferenca-entre-bronquite-e-asma","status":"publish","type":"dicio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/","title":{"rendered":"Qual a diferen\u00e7a entre bronquite e asma?"},"content":{"rendered":"<p>A bronquite \u00e9 uma infec\u00e7\u00e3o nos br\u00f4nquios, localizados nos pulm\u00f5es. Os principais sintomas da bronquite s\u00e3o a tosse (com dura\u00e7\u00e3o superior a 5 dias) e a expectora\u00e7\u00e3o. J\u00e1 a asma \u00e9 uma doen\u00e7a pulmonar cr\u00f4nica, caracterizada por tosse, chiado no peito e falta de ar.<\/p>\n","protected":false},"template":"","class_list":["post-216197","dicio","type-dicio","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Qual a diferen\u00e7a entre bronquite e asma? - Consult\u00f3rios e Cl\u00ednicas<\/title>\n<meta name=\"description\" content=\"Qual a diferen\u00e7a entre bronquite e asma? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a diferen\u00e7a entre bronquite e asma?\" \/>\n<meta property=\"og:description\" content=\"Qual a diferen\u00e7a entre bronquite e asma? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/qual-a-diferenca-entre-bronquite-e-asma\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/qual-a-diferenca-entre-bronquite-e-asma\\\/\",\"name\":\"Qual a diferen\u00e7a entre bronquite e asma? - Consult\u00f3rios e Cl\u00ednicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2021-05-24T15:23:49+00:00\",\"description\":\"Qual a diferen\u00e7a entre bronquite e asma? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/qual-a-diferenca-entre-bronquite-e-asma\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/qual-a-diferenca-entre-bronquite-e-asma\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/qual-a-diferenca-entre-bronquite-e-asma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Base de Dados\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/dicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qual a diferen\u00e7a entre bronquite e asma?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qual a diferen\u00e7a entre bronquite e asma? - Consult\u00f3rios e Cl\u00ednicas","description":"Qual a diferen\u00e7a entre bronquite e asma? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a diferen\u00e7a entre bronquite e asma?","og_description":"Qual a diferen\u00e7a entre bronquite e asma? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/","name":"Qual a diferen\u00e7a entre bronquite e asma? - Consult\u00f3rios e Cl\u00ednicas","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2021-05-24T15:23:49+00:00","description":"Qual a diferen\u00e7a entre bronquite e asma? . D\u00favidas frequentes Sa\u00fade para Todos. Consult\u00f3rios e Cl\u00ednicas","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/qual-a-diferenca-entre-bronquite-e-asma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Base de Dados","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/dicio\/"},{"@type":"ListItem","position":3,"name":"Qual a diferen\u00e7a entre bronquite e asma?"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio\/216197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/dicio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/dicio"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=216197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}