{"id":146384,"date":"2022-02-22T16:30:37","date_gmt":"2022-02-22T19:30:37","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/local\/uniao-de-minas-mg\/"},"modified":"2022-02-22T16:30:37","modified_gmt":"2022-02-22T19:30:37","slug":"uniao-de-minas-mg","status":"publish","type":"local","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/","title":{"rendered":"Uni\u00e3o de Minas &#8211; MG"},"content":{"rendered":"<p><strong>Conhe\u00e7a um pouco sobre o Munic\u00edpio de Uni\u00e3o de Minas &#8211; MG.<\/strong><\/p>\n<p>Uni\u00e3o de Minas \u00e9 uma cidade de Estado do Minas Gerais. Os habitantes se chamam unienses.<\/p>\n<p>A densidade demogr\u00e1fica \u00e9 de 3,8 habitantes por km\u00b2 no territ\u00f3rio do munic\u00edpio. O munic\u00edpio se estende por 1 147,4 km\u00b2 e contava com 4 304 habitantes no \u00faltimo censo.Vizinho dos munic\u00edpios de Limeira do Oeste e Iturama,Uni\u00e3o de Minas se situa a 26 km a Norte-Oeste de Iturama a maior cidade nos arredores.<\/p>\n<p><strong>Como Chegar em Uni\u00e3o de Minas &#8211; Minas Gerais?<\/strong><\/p>\n<p>Situado a 506 metros de altitude, de Uni\u00e3o de Minas tem as seguintes coordenadas geogr\u00e1ficas: Latitude: 19\u00b0 31&#8242; 47&#8221; Sul, Longitude: 50\u00b0 20&#8242; 2&#8221; Oeste<\/p>\n<p>Procure por  <strong>Consult\u00f3rios e Cl\u00ednicas<\/strong> em cidade pr\u00f3xima como Ubaporanga, S\u00e3o Domingos das Dores, Entre Folhas.<\/p>\n","protected":false},"featured_media":0,"template":"","uf":[5743],"class_list":["post-146384","local","type-local","status-publish","hentry","uf-mg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular<\/title>\n<meta name=\"description\" content=\"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uni\u00e3o de Minas - MG\" \/>\n<meta property=\"og:description\" content=\"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/mg\\\/uniao-de-minas-mg\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/mg\\\/uniao-de-minas-mg\\\/\",\"name\":\"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2022-02-22T19:30:37+00:00\",\"description\":\"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/mg\\\/uniao-de-minas-mg\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/mg\\\/uniao-de-minas-mg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/mg\\\/uniao-de-minas-mg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Locais\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/local\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MG\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/mg\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Uni\u00e3o de Minas &#8211; MG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular","description":"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/","og_locale":"pt_BR","og_type":"article","og_title":"Uni\u00e3o de Minas - MG","og_description":"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/","name":"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2022-02-22T19:30:37+00:00","description":"Encontre Consult\u00f3rios e Cl\u00ednicas em Uni\u00e3o de Minas - MG - Somos Popular","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/uniao-de-minas-mg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Locais","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/local\/"},{"@type":"ListItem","position":3,"name":"MG","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/mg\/"},{"@type":"ListItem","position":4,"name":"Uni\u00e3o de Minas &#8211; MG"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/local\/146384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/local"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/local"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=146384"}],"wp:term":[{"taxonomy":"uf","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/uf?post=146384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}