{"id":148487,"date":"2022-05-03T22:54:59","date_gmt":"2022-05-04T01:54:59","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/local\/faxinal-dos-guedes-sc\/"},"modified":"2022-05-03T22:54:59","modified_gmt":"2022-05-04T01:54:59","slug":"faxinal-dos-guedes-sc","status":"publish","type":"local","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/","title":{"rendered":"Faxinal dos Guedes &#8211; SC"},"content":{"rendered":"<p><strong>Conhe\u00e7a um pouco sobre o Munic\u00edpio de Faxinal dos Guedes &#8211; SC.<\/strong><\/p>\n<p>Faxinal dos Guedes \u00e9 uma cidade de Estado do Santa Catarina. Os habitantes se chamam faxinalenses.<\/p>\n<p>A densidade demogr\u00e1fica \u00e9 de 31,4 habitantes por km\u00b2 no territ\u00f3rio do munic\u00edpio. O munic\u00edpio se estende por 339,6 km\u00b2 e contava com 10 667 habitantes no \u00faltimo censo.Vizinho dos munic\u00edpios de Varge\u00e3o, Ouro Verde e Xanxer\u00ea,Faxinal dos Guedes se situa a 15 km a Norte-Leste de Xanxer\u00ea a maior cidade nos arredores.<\/p>\n<p><strong>Como Chegar em Faxinal dos Guedes &#8211; Santa Catarina?<\/strong><\/p>\n<p>Situado a 995 metros de altitude, de Faxinal dos Guedes tem as seguintes coordenadas geogr\u00e1ficas: Latitude: 26\u00b0 51&#8242; 21&#8221; Sul, Longitude: 52\u00b0 15&#8242; 23&#8221; Oeste<\/p>\n<p>Procure por  <strong>Consult\u00f3rios e Cl\u00ednicas<\/strong> em cidade pr\u00f3xima como Coronel Martins, Jupi\u00e1, S\u00e3o Domingos.<\/p>\n","protected":false},"featured_media":0,"template":"","uf":[5746],"class_list":["post-148487","local","type-local","status-publish","hentry","uf-sc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular<\/title>\n<meta name=\"description\" content=\"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faxinal dos Guedes - SC\" \/>\n<meta property=\"og:description\" content=\"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/sc\\\/faxinal-dos-guedes-sc\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/sc\\\/faxinal-dos-guedes-sc\\\/\",\"name\":\"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2022-05-04T01:54:59+00:00\",\"description\":\"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/sc\\\/faxinal-dos-guedes-sc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/sc\\\/faxinal-dos-guedes-sc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/sc\\\/faxinal-dos-guedes-sc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Locais\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/local\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SC\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/sc\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Faxinal dos Guedes &#8211; SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular","description":"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"Faxinal dos Guedes - SC","og_description":"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/","name":"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2022-05-04T01:54:59+00:00","description":"Encontre Consult\u00f3rios e Cl\u00ednicas em Faxinal dos Guedes - SC - Somos Popular","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/faxinal-dos-guedes-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Locais","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/local\/"},{"@type":"ListItem","position":3,"name":"SC","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/sc\/"},{"@type":"ListItem","position":4,"name":"Faxinal dos Guedes &#8211; SC"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/local\/148487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/local"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/local"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=148487"}],"wp:term":[{"taxonomy":"uf","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/uf?post=148487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}