{"id":156047,"date":"2021-04-09T02:46:11","date_gmt":"2021-04-09T05:46:11","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/"},"modified":"2021-04-09T02:46:11","modified_gmt":"2021-04-09T05:46:11","slug":"carlos-adriano-bentes-horta-belem-pa","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/","title":{"rendered":"Carlos Adriano Bentes Horta &#8211; Belem &#8211; PA"},"content":{"rendered":"<p>Consult\u00f3rios e Cl\u00ednicas. A pr\u00e1tica di\u00e1ria as decis\u00f5es tomadas para resolver o problema do paciente s\u00e3o usualmente baseadas na aplica\u00e7\u00e3o consciente da informa\u00e7\u00e3o avali\u00e1vel por regras explicitamente definidas.<\/p>\n<h3>Consultas Popular em Umarizal &#8211; Belem &#8211; PA<\/h3>\n<p><strong>Endere\u00e7o:<\/strong> Avenida Almirante Wandenkolk, 1211  &#8211; Umarizal &#8211; Belem &#8211; PA<br \/>\n<strong>Cep:<\/strong> 66055030<\/p>\n<p><strong>Tipo de Estabelecimento:<\/strong> Ambulat\u00f3rio<br \/>\n<strong>Tipo de Unidade:<\/strong> Consult\u00f3rio<br \/>\n<strong>CNES:<\/strong> 7026900<\/p>\n<h3>Atividade base Reabilita\u00e7\u00e3o<\/h3>\n<p>Conjunto de a\u00e7\u00f5es e servi\u00e7os orientados a desenvolver ou ampliar a capacidade funcional e desempenho dos indiv\u00edduos, proteger a sa\u00fade e prevenir agravos, de modo a contribuir para autonomia, acesso \u00e0 direitos e participa\u00e7\u00e3o em todas as esferas da vida social.<\/p>\n<p><strong>Telefone Carlos Adriano Bentes Horta:<\/strong> 32255270<\/p>\n<p>Encontre Consult\u00f3rios e Cl\u00ednicas em Umarizal &#8211; Belem &#8211; PA<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[5926],"categoria_parceiro":[5721],"class_list":["post-156047","negocio","type-negocio","status-publish","hentry","bairro-umarizal-belem-pa","categoria_parceiro-pediatra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carlos Adriano Bentes Horta - Belem - PA - Somos Popular<\/title>\n<meta name=\"description\" content=\"Carlos Adriano Bentes Horta - Belem - PA. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Umarizal - Belem - PA. Carlos Adriano Bentes Horta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlos Adriano Bentes Horta - Belem - PA\" \/>\n<meta property=\"og:description\" content=\"Carlos Adriano Bentes Horta - Belem - PA. Cl\u00ednica Popular com pre\u00e7os muito mais acess\u00edveis. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Carlos Adriano Bentes Horta - Belem - PA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/carlos-adriano-bentes-horta-belem-pa\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/carlos-adriano-bentes-horta-belem-pa\\\/\",\"name\":\"Carlos Adriano Bentes Horta - Belem - PA - Somos Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2021-04-09T05:46:11+00:00\",\"description\":\"Carlos Adriano Bentes Horta - Belem - PA. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Umarizal - Belem - PA. Carlos Adriano Bentes Horta\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/carlos-adriano-bentes-horta-belem-pa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/carlos-adriano-bentes-horta-belem-pa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/carlos-adriano-bentes-horta-belem-pa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pediatra\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/pediatra\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Carlos Adriano Bentes Horta &#8211; Belem &#8211; PA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carlos Adriano Bentes Horta - Belem - PA - Somos Popular","description":"Carlos Adriano Bentes Horta - Belem - PA. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Umarizal - Belem - PA. Carlos Adriano Bentes Horta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/","og_locale":"pt_BR","og_type":"article","og_title":"Carlos Adriano Bentes Horta - Belem - PA","og_description":"Carlos Adriano Bentes Horta - Belem - PA. Cl\u00ednica Popular com pre\u00e7os muito mais acess\u00edveis. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","twitter_title":"Carlos Adriano Bentes Horta - Belem - PA","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/","name":"Carlos Adriano Bentes Horta - Belem - PA - Somos Popular","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2021-04-09T05:46:11+00:00","description":"Carlos Adriano Bentes Horta - Belem - PA. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Umarizal - Belem - PA. Carlos Adriano Bentes Horta","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/carlos-adriano-bentes-horta-belem-pa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/negocio\/"},{"@type":"ListItem","position":3,"name":"Pediatra","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/pediatra\/"},{"@type":"ListItem","position":4,"name":"Carlos Adriano Bentes Horta &#8211; Belem &#8211; PA"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/negocio\/156047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=156047"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/bairro?post=156047"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/categoria_parceiro?post=156047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}