{"id":183079,"date":"2019-09-05T20:06:01","date_gmt":"2019-09-05T23:06:01","guid":{"rendered":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/"},"modified":"2019-09-05T20:06:01","modified_gmt":"2019-09-05T23:06:01","slug":"nemer-e-nemer-s-s-maringa-pr","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/","title":{"rendered":"Nemer E Nemer S S &#8211; Maringa &#8211; PR"},"content":{"rendered":"<p>Consult\u00f3rios e Cl\u00ednicas. A pr\u00e1tica di\u00e1ria as decis\u00f5es tomadas para resolver o problema do paciente s\u00e3o usualmente baseadas na aplica\u00e7\u00e3o consciente da informa\u00e7\u00e3o avali\u00e1vel por regras explicitamente definidas.<\/p>\n<h3>Consultas Popular em Zona 05 &#8211; Maringa &#8211; PR<\/h3>\n<p><strong>Endere\u00e7o:<\/strong> Av Indepencia 258, 258  &#8211; Zona 05 &#8211; Maringa &#8211; PR<br \/>\n<strong>Cep:<\/strong> 87015020<\/p>\n<p><strong>Tipo de Estabelecimento:<\/strong> Ambulat\u00f3rio<br \/>\n<strong>Tipo de Unidade:<\/strong> Consult\u00f3rio<br \/>\n<strong>CNES:<\/strong> 3668061<\/p>\n<h3>Atividade base Reabilita\u00e7\u00e3o<\/h3>\n<p>Conjunto de a\u00e7\u00f5es e servi\u00e7os orientados a desenvolver ou ampliar a capacidade funcional e desempenho dos indiv\u00edduos, proteger a sa\u00fade e prevenir agravos, de modo a contribuir para autonomia, acesso \u00e0 direitos e participa\u00e7\u00e3o em todas as esferas da vida social.<\/p>\n<p><strong>Telefone Nemer E Nemer S S:<\/strong> <\/p>\n<p>Encontre Consult\u00f3rios e Cl\u00ednicas em Zona 05 &#8211; Maringa &#8211; PR<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[6751],"categoria_parceiro":[5795],"class_list":["post-183079","negocio","type-negocio","status-publish","hentry","bairro-zona-05-maringa-pr","categoria_parceiro-diagnostico-por-imagem-angiorradiologista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nemer E Nemer S S - Maringa - PR - Somos Popular<\/title>\n<meta name=\"description\" content=\"Nemer E Nemer S S - Maringa - PR. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Zona 05 - Maringa - PR. Nemer E Nemer S S\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nemer E Nemer S S - Maringa - PR\" \/>\n<meta property=\"og:description\" content=\"Nemer E Nemer S S - Maringa - PR. Cl\u00ednica Popular com pre\u00e7os muito mais acess\u00edveis. Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/\" \/>\n<meta property=\"og:site_name\" content=\"Consult\u00f3rios e Cl\u00ednicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nemer E Nemer S S - Maringa - PR\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/nemer-e-nemer-s-s-maringa-pr\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/nemer-e-nemer-s-s-maringa-pr\\\/\",\"name\":\"Nemer E Nemer S S - Maringa - PR - Somos Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\"},\"datePublished\":\"2019-09-05T23:06:01+00:00\",\"description\":\"Nemer E Nemer S S - Maringa - PR. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Zona 05 - Maringa - PR. Nemer E Nemer S S\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/nemer-e-nemer-s-s-maringa-pr\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/nemer-e-nemer-s-s-maringa-pr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/nemer-e-nemer-s-s-maringa-pr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diagn\u00f3stico por Imagem: Angiorradiologista\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/diagnostico-por-imagem-angiorradiologista\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nemer E Nemer S S &#8211; Maringa &#8211; PR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\"},\"alternateName\":\"Somos Popular\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#organization\",\"name\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Consult\u00f3rios e Cl\u00ednicas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/consultorios-e-clinicas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nemer E Nemer S S - Maringa - PR - Somos Popular","description":"Nemer E Nemer S S - Maringa - PR. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Zona 05 - Maringa - PR. Nemer E Nemer S S","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/","og_locale":"pt_BR","og_type":"article","og_title":"Nemer E Nemer S S - Maringa - PR","og_description":"Nemer E Nemer S S - Maringa - PR. Cl\u00ednica Popular com pre\u00e7os muito mais acess\u00edveis. Consult\u00f3rios e Cl\u00ednicas","og_url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/","og_site_name":"Consult\u00f3rios e Cl\u00ednicas","twitter_card":"summary_large_image","twitter_title":"Nemer E Nemer S S - Maringa - PR","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/","name":"Nemer E Nemer S S - Maringa - PR - Somos Popular","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website"},"datePublished":"2019-09-05T23:06:01+00:00","description":"Nemer E Nemer S S - Maringa - PR. Consultar Agenda e Telefone Consult\u00f3rios e Cl\u00ednicas em Zona 05 - Maringa - PR. Nemer E Nemer S S","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/nemer-e-nemer-s-s-maringa-pr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/negocio\/"},{"@type":"ListItem","position":3,"name":"Diagn\u00f3stico por Imagem: Angiorradiologista","item":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/diagnostico-por-imagem-angiorradiologista\/"},{"@type":"ListItem","position":4,"name":"Nemer E Nemer S S &#8211; Maringa &#8211; PR"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#website","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization"},"alternateName":"Somos Popular","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#organization","name":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-content\/uploads\/sites\/2\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Consult\u00f3rios e Cl\u00ednicas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/negocio\/183079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/media?parent=183079"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/bairro?post=183079"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/consultorios-e-clinicas\/wp-json\/wp\/v2\/categoria_parceiro?post=183079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}