{"id":150929,"date":"2022-01-20T12:58:38","date_gmt":"2022-01-20T15:58:38","guid":{"rendered":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/"},"modified":"2022-01-20T12:58:38","modified_gmt":"2022-01-20T15:58:38","slug":"odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/","title":{"rendered":"Odontopediatria Popular &#8211; Dentista Popular em Jardim Gumercindo &#8211; Guarulhos &#8211; SP"},"content":{"rendered":"<p>A Dentz est\u00e1 entre as mais modernas e inovadoras Cl\u00ednicas Odontol\u00f3gicas do Brasil, formada por uma equipe de incr\u00edveis dentistas oferece os melhores tratamentos odontol\u00f3gicos com a melhor qualidade em todas as especialidades. Ortodontia, cl\u00ednico, implantes, pr\u00f3teses, odontopediatria, periodontia, est\u00e9tica, cirurgias e muito mais. Queremos ver voc\u00ea sorrir. Sorrir bem e sorrir sempre. Confie na dentz, n\u00f3s cuidaremos do seu sorriso. Para n\u00f3s, ele \u00e9 \u00fanico :).<br \/>\nNa Dentz, acreditamos que sonhar \u00e9 um exerc\u00edcio a ser levado a s\u00e9rio.<br \/>\nQue tra\u00e7ar metas para atingir os sonhos \u00e9 determinante.<br \/>\nE que trabalhar incansavelmente para realiz\u00e1-los \u00e9 o que diferencia grandes empreendedores.<br \/>\nA Dentz criou um modelo de neg\u00f3cio vencedor para realizar sonhos.<br \/>\nOs tratamentos est\u00e9ticos dentais profissionais v\u00e3o ajudar voc\u00ea a ter resultados est\u00e9ticos incr\u00edveis com longa dura\u00e7\u00e3o, melhorando sua autoestima e confian\u00e7a. Nossa odontologia est\u00e1 estruturada para atender seus desejos e necessidades, utilizando as mais modernas t\u00e9cnicas restauradoras e prot\u00e9ticas, proporcionando a reabilita\u00e7\u00e3o da fun\u00e7\u00e3o mastigat\u00f3ria e o desenvolvimento da beleza est\u00e9tica.<\/p>\n<h3>Tratamentos Est\u00e9ticos<\/h3>\n<p>O mais conhecido e procurado tipo de tratamento est\u00e9tico \u00e9 o Clareamento ou Branqueamento dental. Oferecemos o tratamento de Clareamento a Laser na Cl\u00ednica e o Clareamento Caseiro Monitorado. Tamb\u00e9m somos especializados nos tratamentos est\u00e9ticos de Faceta Dental, Lentes de Contato Dentais, Bichectomia, Piercing Dental e Preenchimento Facial.<br \/>\nO Corpo Cl\u00ednico da rede Dentz \u00e9 composto por profissionais altamente qualificados de diversas especialidades, incluindo Mestres e Doutores. Estamos preparados para direcionar e realizar cirurgias complexas e tratamentos especiais como a Periodontia e Placa Antirronco, por exemplo. A Periodontia \u00e9 a especialidade odontol\u00f3gica que permite a preven\u00e7\u00e3o e o tratamento das doen\u00e7as que afetam os tecidos de sustenta\u00e7\u00e3o e prote\u00e7\u00e3o dos dentes (tratamento da gengiva e do osso).<br \/>\nA Placa Antirronco vai permitir ao paciente voltar a dormir em paz. A apneia do sono geralmente \u00e9 decorrente da flacidez dos tecidos da garganta que obstroem a passagem do ar.<br \/>\n\u200bA ortodontia \u00e9 a \u00e1rea da odontologia que atua na corre\u00e7\u00e3o de problemas relacionados \u00e0 posi\u00e7\u00e3o dos dentes e que estuda o crescimento e forma\u00e7\u00e3o da face e do desenvolvimento das denti\u00e7\u00f5es de leite (dec\u00eddua), mista e permanente e seus poss\u00edveis desvios. Por meio dos aparelhos ortod\u00f4nticos, realiza-se a preven\u00e7\u00e3o, intercepta\u00e7\u00e3o e corre\u00e7\u00e3o completa, seja em casos de pequenas imperfei\u00e7\u00f5es ou problemas dentais mais avan\u00e7ados.<\/p>\n<h3>Tipos de Aparelhos<\/h3>\n<p>O tratamento ortod\u00f4ntico pode ser realizados por diferentes t\u00e9cnicas e tipos de aparelho. A rede de cl\u00ednicas Dentz oferece a maior variedade desses aparelhos, como o Fixo, o Fixo Est\u00e9tico, o Autoligado, Aparelhos M\u00f3veis e Extra Bucais e o Expansor Palatino.<br \/>\nH\u00e1 casos em que o paciente tem a op\u00e7\u00e3o de escolher entre aparelhos que possuem a mesma fun\u00e7\u00e3o, mas geralmente, a defini\u00e7\u00e3o do tipo de aparelho que o paciente precisar\u00e1 utilizar \u00e9 o seu diagn\u00f3stico espec\u00edfico ou a sua idade. Nossos ortodontistas est\u00e3o preparados para diagnosticar seu problema e desenhar um tratamento definitivo e seguro.<br \/>\nA cl\u00ednica geral \u00e9 a sua porta de entrada no universo da odontologia e a \u00e1rea mais ampla de tratamentos. Por meio desta atividade \u00e9 que podemos diagnosticar as necessidades, altera\u00e7\u00f5es e problemas do paciente. A partir deste panorama diagn\u00f3stico, desenha-se um plano de tratamento espec\u00edfico e personalizado, encaminhando o paciente para as outras especialidades odontol\u00f3gicas, quando for o caso.<\/p>\n<h3>Tipos de Procedimentos<\/h3>\n<p>S\u00e3o muitos os procedimentos realizados pela cl\u00ednica geral:<br \/>\nProfilaxia (limpeza), Remo\u00e7\u00e3o de T\u00e1rtaro, Aplica\u00e7\u00e3o de Fl\u00faor, Orienta\u00e7\u00e3o T\u00e9cnica de Higiene Bucal, Remo\u00e7\u00e3o de C\u00e1ries, Confec\u00e7\u00e3o e Ajustes de Restaura\u00e7\u00f5es, Tratamento de Canais de menor ou maior complexidade (Endodontia), Cirurgias Orais, Tratamento de Bruxismo, Selantes e Procedimentos de Urg\u00eancia.<\/p>\n<h3>IMPLANTES<\/h3>\n<p>Com os melhores profissionais, t\u00e9cnicas e tecnologias dispon\u00edveis, a Dentz pode ajudar voc\u00ea a voltar a sorrir com alegria e confian\u00e7a, tendo uma sensa\u00e7\u00e3o de naturalidade visual e conforto mastigat\u00f3rio. Os implantes s\u00e3o cilindros de tit\u00e2nio instalados nos ossos maxilares para a substitui\u00e7\u00e3o de ra\u00edzes de dentes ausentes. O protocolo de um implante \u00e9 realizado em duas fases:<br \/>\nPrimeiro: Cirurgia, indolor (tanto na cirurgia, quanto no p\u00f3s-operat\u00f3rio) com a instala\u00e7\u00e3o do implante nos ossos maxilares e a osteointegra\u00e7\u00e3o (per\u00edodo de espera para a conex\u00e3o ideal).<br \/>\nSegundo: Parte Prot\u00e9tica, onde \u00e9 elaborada a pr\u00f3tese sobre os implantes. A fixa\u00e7\u00e3o ocorre por meio de parafusos (interiores e recobertos por resina da cor do dente) que permitem a retirada dos implantes para manuten\u00e7\u00e3o (apenas pelo Dentista).<\/p>\n<h3>PR\u00d3TESES<\/h3>\n<p>As Pr\u00f3teses s\u00e3o a solu\u00e7\u00e3o para o problema de muitos brasileiros. Com foco no tratamento com pr\u00f3tese fixa, a Dentz tamb\u00e9m pode ajud\u00e1-lo a encontrar sua solu\u00e7\u00e3o com pr\u00f3teses remov\u00edveis. O tratamento com uma pr\u00f3tese ser\u00e1 destinado \u00e0 reconstru\u00e7\u00e3o e reposi\u00e7\u00e3o de elementos dent\u00e1rios danificados ou perdidos, devolvendo ao paciente as caracter\u00edsticas e fun\u00e7\u00f5es mastigat\u00f3rias, est\u00e9ticas e fon\u00e9ticas, al\u00e9m de recompor e proteger fun\u00e7\u00f5es articulares.<br \/>\nOs tratamentos est\u00e9ticos dentais profissionais v\u00e3o ajudar voc\u00ea a ter resultados est\u00e9ticos incr\u00edveis com longa dura\u00e7\u00e3o, melhorando sua autoestima e confian\u00e7a. Nossa odontologia est\u00e1 estruturada para atender seus desejos e necessidades, utilizando as mais modernas t\u00e9cnicas restauradoras e prot\u00e9ticas, proporcionando a reabilita\u00e7\u00e3o da fun\u00e7\u00e3o mastigat\u00f3ria e o desenvolvimento da beleza est\u00e9tica.<\/p>\n<h3>Tratamentos Est\u00e9ticos<\/h3>\n<p>O mais conhecido e procurado tipo de tratamento est\u00e9tico \u00e9 o Clareamento ou Branqueamento dental. Oferecemos o tratamento de Clareamento a Laser na Cl\u00ednica e o Clareamento Caseiro Monitorado. Tamb\u00e9m somos especializados nos tratamentos est\u00e9ticos de Faceta Dental, Lentes de Contato Dentais, Bichectomia, Piercing Dental e Preenchimento Facial.<\/p>\n<h3>Kids<\/h3>\n<p>Mam\u00e3e e papai, criamos uma estrutura amig\u00e1vel e inovadora para realizar o tratamento odontol\u00f3gico completo para seu menino ou menina! Seja para a Aplica\u00e7\u00e3o de Fluor ou Selante, Ortodontia Infantil, Educa\u00e7\u00e3o e Higieniza\u00e7\u00e3o ou Remo\u00e7\u00e3o de C\u00e1ries, nossa estrutura est\u00e1 pronta para atender sua crian\u00e7a de qualquer idade com o cuidado, paci\u00eancia e carinho que merece.<br \/>\nAgende agora uma consulta via WhatsApp<\/p>\n<h3>Odontopediatria Popular &#8211; Dentista Popular em Jardim Gumercindo &#8211; Guarulhos &#8211; SP<\/h3>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[6865],"categoria_parceiro":[6759,6752,6858],"class_list":["post-150929","negocio","type-negocio","status-publish","hentry","bairro-jardim-gumercindo-guarulhos-sp","categoria_parceiro-dentista-popular","categoria_parceiro-odontologia","categoria_parceiro-odontopediatria-popular"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP<\/title>\n<meta name=\"description\" content=\"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP. Agendar consulta Dentista Popular\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP\" \/>\n<meta property=\"og:description\" content=\"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP. Cl\u00ednica Popular com pre\u00e7os muito mais acess\u00edveis. Dentistas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Dentistas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\\\/\",\"name\":\"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/#website\"},\"datePublished\":\"2022-01-20T15:58:38+00:00\",\"description\":\"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP. Agendar consulta Dentista Popular\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Odontologia\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dentista Popular\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/dentista-popular\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Odontopediatria Popular &#8211; Dentista Popular em Jardim Gumercindo &#8211; Guarulhos &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/\",\"name\":\"Dentistas - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/#organization\",\"name\":\"Dentistas - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Dentistas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/dentistas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP","description":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP. Agendar consulta Dentista Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP","og_description":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP. Cl\u00ednica Popular com pre\u00e7os muito mais acess\u00edveis. Dentistas","og_url":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/","og_site_name":"Dentistas","twitter_card":"summary_large_image","twitter_title":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/","url":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/","name":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/dentistas\/#website"},"datePublished":"2022-01-20T15:58:38+00:00","description":"Odontopediatria Popular - Dentista Popular em Jardim Gumercindo - Guarulhos - SP. Agendar consulta Dentista Popular","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/dentistas\/odontopediatria-popular-dentista-popular-jardim-gumercindo-guarulhos-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Odontologia","item":"https:\/\/www.somospopular.com.br\/dentistas\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/dentistas\/negocio\/"},{"@type":"ListItem","position":3,"name":"Dentista Popular","item":"https:\/\/www.somospopular.com.br\/dentistas\/dentista-popular\/"},{"@type":"ListItem","position":4,"name":"Odontopediatria Popular &#8211; Dentista Popular em Jardim Gumercindo &#8211; Guarulhos &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/dentistas\/#website","url":"https:\/\/www.somospopular.com.br\/dentistas\/","name":"Dentistas - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/dentistas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/dentistas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/dentistas\/#organization","name":"Dentistas - Somos Popular","url":"https:\/\/www.somospopular.com.br\/dentistas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/dentistas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/dentistas\/wp-content\/uploads\/sites\/5\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/dentistas\/wp-content\/uploads\/sites\/5\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Dentistas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/dentistas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/negocio\/150929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/media?parent=150929"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/bairro?post=150929"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/dentistas\/wp-json\/wp\/v2\/categoria_parceiro?post=150929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}