{"id":174286,"date":"2021-12-01T11:45:38","date_gmt":"2021-12-01T14:45:38","guid":{"rendered":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-al\/"},"modified":"2023-05-20T18:10:56","modified_gmt":"2023-05-20T21:10:56","slug":"dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/","title":{"rendered":"Dra. Maria Clotildes de Albuquerque Mendes &#8211; An\u00e1tomopatologista Penedo &#8211; AL"},"content":{"rendered":"<h2>An\u00e1tomopatologista em Arapiraca &#8211; AL<\/h2>\n<p><strong>Endere\u00e7o:<\/strong> Avenida Rio Branco, 334, Centro, Arapiraca &#8211; AL<br \/>\n<strong>CEP: <\/strong>57300-190<\/p>\n<p><span class=\"phone-hidden\"><strong>Telefone:<\/strong>  <\/span><\/p>\n<h2>Dra. Maria Clotildes de Albuquerque Mendes &#8211; An\u00e1tomopatologista Penedo<\/h2>\n<p>Dra. Maria Clotildes de Albuquerque Mendes, An\u00e1tomopatologista em Penedo. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil.<\/p>\n<p><span class=\"maps-hidden\"><a href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=Avenida Rio Branco, 334, Centro, Arapiraca - AL - 57300-190\" target=\"_blank\" rel=\"noopener\">COMO CHEGAR?<\/a><\/span><\/p>\n<hr \/>\n<ul>\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20alergia%20a%20medicamentos%20blumenau\" title=\"Alergia a medicamentos\" class=\"textbody\">Alergia a medicamentos<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20asma%20em%20criancas%20blumenau\" title=\"Asma em crian\u00e7as\" class=\"textbody\">Asma em crian\u00e7as<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20eczema%20e%20dermatite%20atopica%20blumenau\" title=\"Eczema e dermatite at\u00f3pica\" class=\"textbody\">Eczema e dermatite at\u00f3pica<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20anafilaxia%20blumenau\" class=\"textbody\"><br \/>\n\t\tAnafilaxia<br \/>\n\t<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20alergias%20alimentares%202%20blumenau\" title=\"Alergias alimentares\" class=\"textbody\">Alergias alimentares<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20alergia%20aos%20acaros%20do%20po%20blumenau\" title=\"Alergia aos \u00e1caros do p\u00f3\" class=\"textbody\">Alergia aos \u00e1caros do p\u00f3<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20conjuntivite%20alergica%20blumenau\" class=\"textbody\"><br \/>\n\t\tConjuntivite Al\u00e9rgica<br \/>\n\t<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20doencas%20alergicas%20blumenau\" title=\"Doen\u00e7as al\u00e9rgicas\" class=\"textbody\">Doen\u00e7as al\u00e9rgicas<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20hipersensibilidade%20ao%20latex%20blumenau\" class=\"textbody\"><br \/>\n\t\tHipersensibilidade Ao L\u00e1tex<br \/>\n\t<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20dermatite%20de%20contato%20blumenau\" title=\"Dermatite de contato\" class=\"textbody\">Dermatite de contato<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20urticaria%20blumenau\" class=\"textbody\"><br \/>\n\t\tUrtic\u00e1ria<br \/>\n\t<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20rinite%20alergica%20perene%20blumenau\" class=\"textbody\"><br \/>\n\t\tRinite Al\u00e9rgica Perene<br \/>\n\t<\/a><\/li>\n<\/ul>\n<hr \/>\n<p><strong>T\u00f3picos:<\/strong> An\u00e1tomopatologista em Arapiraca &#8211; AL <span class=\"topic-hidden\">|   <\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[6303],"categoria_parceiro":[20453],"topico-parceiro":[26731],"class_list":["post-174286","negocio","type-negocio","status-publish","hentry","bairro-centro-arapiraca-al","categoria_parceiro-anatomopatologista","topico-parceiro-anatomopatologista-em-arapiraca-al"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL<\/title>\n<meta name=\"description\" content=\"Dra. Maria Clotildes de Albuquerque Mendes, An\u00e1tomopatologista em Penedo. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL\" \/>\n<meta property=\"og:description\" content=\"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Especialistas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/\" \/>\n<meta property=\"og:site_name\" content=\"Especialistas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-20T21:10:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\\\/\",\"name\":\"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#website\"},\"datePublished\":\"2021-12-01T14:45:38+00:00\",\"dateModified\":\"2023-05-20T21:10:56+00:00\",\"description\":\"Dra. Maria Clotildes de Albuquerque Mendes, An\u00e1tomopatologista em Penedo. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Especialista\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"An\u00e1tomopatologista\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/anatomopatologista\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dra. Maria Clotildes de Albuquerque Mendes &#8211; An\u00e1tomopatologista Penedo &#8211; AL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/\",\"name\":\"Especialistas\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#organization\",\"name\":\"M\u00e9dicos Especialistas - Somos Popular\",\"alternateName\":\"M\u00e9dicos Especialistas\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"M\u00e9dicos Especialistas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL","description":"Dra. Maria Clotildes de Albuquerque Mendes, An\u00e1tomopatologista em Penedo. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/","og_locale":"pt_BR","og_type":"article","og_title":"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL","og_description":"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Especialistas","og_url":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/","og_site_name":"Especialistas","article_modified_time":"2023-05-20T21:10:56+00:00","twitter_card":"summary_large_image","twitter_title":"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/","url":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/","name":"Dra. Maria Clotildes de Albuquerque Mendes - An\u00e1tomopatologista Penedo - AL","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/#website"},"datePublished":"2021-12-01T14:45:38+00:00","dateModified":"2023-05-20T21:10:56+00:00","description":"Dra. Maria Clotildes de Albuquerque Mendes, An\u00e1tomopatologista em Penedo. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil.","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/especialistas\/dra-maria-clotildes-de-albuquerque-mendes-anatomopatologista-em-arapiraca-al\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Especialista","item":"https:\/\/www.somospopular.com.br\/especialistas\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/especialistas\/negocio\/"},{"@type":"ListItem","position":3,"name":"An\u00e1tomopatologista","item":"https:\/\/www.somospopular.com.br\/especialistas\/anatomopatologista\/"},{"@type":"ListItem","position":4,"name":"Dra. Maria Clotildes de Albuquerque Mendes &#8211; An\u00e1tomopatologista Penedo &#8211; AL"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/especialistas\/#website","url":"https:\/\/www.somospopular.com.br\/especialistas\/","name":"Especialistas","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/especialistas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/especialistas\/#organization","name":"M\u00e9dicos Especialistas - Somos Popular","alternateName":"M\u00e9dicos Especialistas","url":"https:\/\/www.somospopular.com.br\/especialistas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/especialistas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/especialistas\/wp-content\/uploads\/sites\/13\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/especialistas\/wp-content\/uploads\/sites\/13\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"M\u00e9dicos Especialistas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/negocio\/174286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/media?parent=174286"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/bairro?post=174286"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/categoria_parceiro?post=174286"},{"taxonomy":"topico-parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/topico-parceiro?post=174286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}