{"id":175011,"date":"2022-07-10T07:25:09","date_gmt":"2022-07-10T10:25:09","guid":{"rendered":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-go\/"},"modified":"2023-05-20T18:20:06","modified_gmt":"2023-05-20T21:20:06","slug":"dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/","title":{"rendered":"Dra. Rebecca Da Costa e Silva Paz &#8211; Dermatologista Goian\u00e9sia &#8211; GO"},"content":{"rendered":"<p>Forma\u00e7\u00e3o m\u00e9dica e experi\u00eancia profissional<br \/>\nMedicina &#8211; Escola Paulista de Medicina\/Universidade Federal de S\u00e3o Paulo (UNIFESP);<br \/>\nResid\u00eancia M\u00e9dica em Dermatologia &#8211; Escola Paulista de Medicina\/Universidade Federal de S\u00e3o Paulo (UNIFESP);<br \/>\nDermatologista na Cl\u00ednica Nuno Os\u00f3rio (S\u00e3o Paulo-SP) &#8211; 2018 a 2022;<br \/>\nDocente do Instituto Boggio;<br \/>\nDoutoranda em Medicina Translacional &#8211; Escola Paulista de Medicina\/Universidade Federal de S\u00e3o Paulo (UNIFESP);<br \/>\nMembro da Sociedade Brasileira de Dermatologia.<br \/>\nIniciei minha trajet\u00f3ria na medicina ao ingressar, em 2009, na Universidade Federal de S\u00e3o Paulo, tamb\u00e9m conhecida como Escola Paulista de Medicina. Naquele momento se iniciava um grande sonho, que ja vinha sendo sonhado e constru\u00eddo com muito esfor\u00e7o e dedica\u00e7\u00e3o. A Escola onde eu viveria meus pr\u00f3ximos 6 anos \u00e9 uma das mais reconhecidas institui\u00e7\u00f5es de ensino e pesquisa m\u00e9dica do mundo.<br \/>\nSeis anos se passaram, mas o amor pela Escola s\u00f3 aumentava.<br \/>\nAp\u00f3s me formar m\u00e9dica, em 2014, conquistei uma vaga em um dos programas de resid\u00eancia m\u00e9dica mais concorridos do pa\u00eds: Dermatologia, ainda na Universidade Federal de S\u00e3o Paulo, que neste momento j\u00e1 era minha segunda casa.<br \/>\nA resid\u00eancia de dermatologia conta com um programa de 3 anos, durante os quais aprendemos a fundo tudo o que se refere \u00e0s doen\u00e7as de pele, cabelos e unhas, bem como os tratamentos cl\u00ednicos e cir\u00fargicos para cada uma dessas condi\u00e7\u00f5es.<br \/>\nCom o t\u00e9rmino da resid\u00eancia, em 2018, vinha um novo desafio na carreira: a prova de t\u00edtulo de especialista em Dermatologia, na qual fui aprovada neste mesmo ano.<br \/>\nEm seguida, logo ap\u00f3s concluir a resid\u00eancia, fui convidada a integrar a equipe de m\u00e9dicos de uma das mais tradicionais cl\u00ednicas de Dermatologia do Brasil &#8211; A Cl\u00ednica Nuno Os\u00f3rio, na cidade de S\u00e3o Paulo. De 2018 a 2022 trabalhei ao lado de m\u00e9dicos incr\u00edveis e em contato com as mais modernas tecnologias. A cl\u00ednica se destaca pelos tratamentos em cosmiatria e pelo pioneirismo do dr. Nuno Os\u00f3rio no campo do laser dermatol\u00f3gico no pa\u00eds.<br \/>\nFoi durante esse tempo que a paix\u00e3o pela cosmiatria cresceu. No final de 2021, percebi que deveria dividir com outras pessoas tudo o que tive o privil\u00e9gio de aprender nessa minha trajet\u00f3ria. Ap\u00f3s passar por um processo seletivo, integrei o corpo docente do Instituto Boggio, renomada institui\u00e7\u00e3o de ensino m\u00e9dico e cosmi\u00e1trico, que tem \u00e0 frente o Dr. Ricardo Boggio, cirurgi\u00e3o pl\u00e1stico de grande experi\u00eancia no campo da cosmiatria.<br \/>\nSem conseguir deixar minha amada Escola Paulista, fui aprovada como aluna de p\u00f3s-gradua\u00e7\u00e3o no Doutorado da Medicina Translacional, onde conduzo um estudo cl\u00ednico que envolve o uso da toxina botul\u00ednica no processo de cicatriza\u00e7\u00e3o.<br \/>\nNo come\u00e7o de 2022, dei in\u00edcio a um novo e muito especial ciclo em minha vida &#8211; a inaugura\u00e7\u00e3o da Reviq\u00e1 Dermatologia (na cidade de Itaja\u00ed-SC) que, muito mais do que minha primeira cl\u00ednica, \u00e9 um grande sonho que foi feito para ser compartilhado com cada um dos meus pacientes, com todo o carinho e a dedica\u00e7\u00e3o que couberem a mim.<\/p>\n<h2>Dermatologista em Goian\u00e9sia &#8211; GO<\/h2>\n<p><strong>Endere\u00e7o:<\/strong> Rua 33 430, Centro, Goian\u00e9sia &#8211; GO<br \/>\n<strong>CEP: <\/strong>76380-124<\/p>\n<p><span class=\"phone-hidden\"><strong>Telefone:<\/strong>  <\/span><\/p>\n<h2>Dra. Rebecca Da Costa e Silva Paz &#8211; Dermatologista Goian\u00e9sia<\/h2>\n<p>Dra. Rebecca Da Costa e Silva Paz, Dermatologista em Goian\u00e9sia. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil. Transplante Capilar, Calv\u00edcie Feminina E Masculina.<\/p>\n<p><span class=\"maps-hidden\"><a href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=Rua 33 430, Centro, Goian\u00e9sia - GO - 76380-124\" target=\"_blank\" rel=\"noopener\">COMO CHEGAR?<\/a><\/span><\/p>\n<h3 class=\"flex-grow-1 mb-0\">Experi\u00eancia<\/h3>\n<hr \/>\n<ul>\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20varizes%20porto%20alegre\" title=\"Varizes\" class=\"textbody\">Varizes<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20pe%20diabetico%20porto%20alegre\" title=\"P\u00e9 Diab\u00e9tico\" class=\"textbody\">P\u00e9 Diab\u00e9tico<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20trombose%20porto%20alegre\" title=\"Trombose\" class=\"textbody\">Trombose<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20ulcera%20varicosa%20porto%20alegre\" title=\"\u00dalcera Varicosa\" class=\"textbody\">\u00dalcera Varicosa<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20varizes%20nas%20pernas%20porto%20alegre\" title=\"Varizes nas pernas\" class=\"textbody\">Varizes nas pernas<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20insuficiencia%20venosa%20porto%20alegre\" title=\"Insufici\u00eancia Venosa\" class=\"textbody\">Insufici\u00eancia Venosa<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20aneurisma%20porto%20alegre\" title=\"Aneurisma\" class=\"textbody\">Aneurisma<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20doencas%20das%20arterias%20carotidas%20porto%20alegre\" title=\"Doen\u00e7as Das Art\u00e9rias Car\u00f3tidas\" class=\"textbody\">Doen\u00e7as Das Art\u00e9rias Car\u00f3tidas<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20embolia%20e%20trombose%20porto%20alegre\" title=\"Embolia E Trombose\" class=\"textbody\">Embolia E Trombose<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20doencas%20vasculares%20perifericas%20porto%20alegre\" title=\"Doen\u00e7as Vasculares Perif\u00e9ricas\" class=\"textbody\">Doen\u00e7as Vasculares Perif\u00e9ricas<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20claudicacao%20intermitente%20porto%20alegre\" title=\"Claudica\u00e7\u00e3o Intermitente\" class=\"textbody\">Claudica\u00e7\u00e3o Intermitente<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20doenca%20de%20raynaud%20porto%20alegre\" title=\"Doen\u00e7a de raynaud\" class=\"textbody\">Doen\u00e7a de raynaud<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20vasculite%20porto%20alegre\" title=\"Vasculite\" class=\"textbody\">Vasculite<\/a><\/li>\n<hr >\n<li><a href=\"\/especialistas\/#gsc.tab=0&#038;gsc.q=Especialista%20em%20malformacoes%20arteriovenosas%20porto%20alegre\" title=\"Malforma\u00e7\u00f5es Arteriovenosas\" class=\"textbody\">Malforma\u00e7\u00f5es Arteriovenosas<\/a><\/li>\n<hr >\n<li>\n<p>Cirurgia de varizes\t\t\t\t<\/li>\n<hr >\n<li>\n<p>Fistula para hemodi\u00e1lise\t\t\t\t<\/li>\n<hr >\n<li>\n<p>Ulcera venosa\t\t\t\t<\/li>\n<hr >\n<li>\n<p>Aterosclerose\t\t\t\t<\/li>\n<hr >\n<li>\n<p>Doen\u00e7a Oclusiva Perif\u00e9rica\t\t\t\t<\/li>\n<hr >\n<li>\n<p>Fistula arteriovenosa\t\t\t\t<\/li>\n<\/ul>\n<hr \/>\n<p><strong>T\u00f3picos:<\/strong> Dermatologista em Goian\u00e9sia &#8211; GO <span class=\"topic-hidden\">|   Cl\u00ednica CMA &#8211; Centro de Medicina Avan\u00e7ada<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[24057],"categoria_parceiro":[20537],"topico-parceiro":[20909],"class_list":["post-175011","negocio","type-negocio","status-publish","hentry","bairro-centro-goianesia-go","categoria_parceiro-dermatologista","topico-parceiro-dermatologista-em-goianesia-go"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO<\/title>\n<meta name=\"description\" content=\"Dra. Rebecca Da Costa e Silva Paz, Dermatologista em Goian\u00e9sia. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil. Transplante Capilar, Calv\u00edcie Feminina E Masculina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO\" \/>\n<meta property=\"og:description\" content=\"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Especialistas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/\" \/>\n<meta property=\"og:site_name\" content=\"Especialistas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-20T21:20:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\\\/\",\"name\":\"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#website\"},\"datePublished\":\"2022-07-10T10:25:09+00:00\",\"dateModified\":\"2023-05-20T21:20:06+00:00\",\"description\":\"Dra. Rebecca Da Costa e Silva Paz, Dermatologista em Goian\u00e9sia. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil. Transplante Capilar, Calv\u00edcie Feminina E Masculina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Especialista\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dermatologista\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/dermatologista\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dra. Rebecca Da Costa e Silva Paz &#8211; Dermatologista Goian\u00e9sia &#8211; GO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/\",\"name\":\"Especialistas\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#organization\",\"name\":\"M\u00e9dicos Especialistas - Somos Popular\",\"alternateName\":\"M\u00e9dicos Especialistas\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"M\u00e9dicos Especialistas - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/especialistas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO","description":"Dra. Rebecca Da Costa e Silva Paz, Dermatologista em Goian\u00e9sia. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil. Transplante Capilar, Calv\u00edcie Feminina E Masculina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/","og_locale":"pt_BR","og_type":"article","og_title":"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO","og_description":"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Especialistas","og_url":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/","og_site_name":"Especialistas","article_modified_time":"2023-05-20T21:20:06+00:00","twitter_card":"summary_large_image","twitter_title":"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/","url":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/","name":"Dra. Rebecca Da Costa e Silva Paz - Dermatologista Goian\u00e9sia - GO","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/#website"},"datePublished":"2022-07-10T10:25:09+00:00","dateModified":"2023-05-20T21:20:06+00:00","description":"Dra. Rebecca Da Costa e Silva Paz, Dermatologista em Goian\u00e9sia. Agende uma consulta com os melhores profissionais de sa\u00fade em Brasil. Transplante Capilar, Calv\u00edcie Feminina E Masculina.","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/especialistas\/dra-rebecca-da-costa-e-silva-paz-dermatologista-em-goianesia-go\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Especialista","item":"https:\/\/www.somospopular.com.br\/especialistas\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/especialistas\/negocio\/"},{"@type":"ListItem","position":3,"name":"Dermatologista","item":"https:\/\/www.somospopular.com.br\/especialistas\/dermatologista\/"},{"@type":"ListItem","position":4,"name":"Dra. Rebecca Da Costa e Silva Paz &#8211; Dermatologista Goian\u00e9sia &#8211; GO"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/especialistas\/#website","url":"https:\/\/www.somospopular.com.br\/especialistas\/","name":"Especialistas","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/especialistas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/especialistas\/#organization","name":"M\u00e9dicos Especialistas - Somos Popular","alternateName":"M\u00e9dicos Especialistas","url":"https:\/\/www.somospopular.com.br\/especialistas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/especialistas\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/especialistas\/wp-content\/uploads\/sites\/13\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/especialistas\/wp-content\/uploads\/sites\/13\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"M\u00e9dicos Especialistas - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/especialistas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/negocio\/175011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/media?parent=175011"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/bairro?post=175011"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/categoria_parceiro?post=175011"},{"taxonomy":"topico-parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/especialistas\/wp-json\/wp\/v2\/topico-parceiro?post=175011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}