{"id":11364,"count":1,"description":"","link":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/","name":"Vila Tupi - Bertioga - SP","slug":"vila-tupi-bertioga-sp","taxonomy":"bairro","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos - Somos Popular<\/title>\n<meta name=\"description\" content=\"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos. Agende exames emVila Tupi - Bertioga - SP\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Vila Tupi - Bertioga - SP\" \/>\n<meta property=\"og:description\" content=\"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos. Agende exames emVila Tupi - Bertioga - SP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Exames e Diagn\u00f3sticos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/vila-tupi-bertioga-sp\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/vila-tupi-bertioga-sp\\\/\",\"name\":\"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos - Somos Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/#website\"},\"description\":\"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos. Agende exames emVila Tupi - Bertioga - SP\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/vila-tupi-bertioga-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/vila-tupi-bertioga-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Exames\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vila Tupi - Bertioga - SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/\",\"name\":\"Exames e Diagn\u00f3sticos - Somos Popular\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/#organization\",\"name\":\"Exames e Diagn\u00f3sticos - Somos Popular\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Exames e Diagn\u00f3sticos - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/exames\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos - Somos Popular","description":"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos. Agende exames emVila Tupi - Bertioga - SP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Vila Tupi - Bertioga - SP","og_description":"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos. Agende exames emVila Tupi - Bertioga - SP","og_url":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/","og_site_name":"Exames e Diagn\u00f3sticos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/","url":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/","name":"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos - Somos Popular","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/exames\/#website"},"description":"Exames Popular em Vila Tupi - Bertioga - SP - Exames e Diagn\u00f3sticos. Agende exames emVila Tupi - Bertioga - SP","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/exames\/vila-tupi-bertioga-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Exames","item":"https:\/\/www.somospopular.com.br\/exames\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/exames\/negocio\/"},{"@type":"ListItem","position":3,"name":"Vila Tupi - Bertioga - SP"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/exames\/#website","url":"https:\/\/www.somospopular.com.br\/exames\/","name":"Exames e Diagn\u00f3sticos - Somos Popular","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/exames\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/exames\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/exames\/#organization","name":"Exames e Diagn\u00f3sticos - Somos Popular","url":"https:\/\/www.somospopular.com.br\/exames\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/exames\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/exames\/wp-content\/uploads\/sites\/9\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/exames\/wp-content\/uploads\/sites\/9\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Exames e Diagn\u00f3sticos - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/exames\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/exames\/wp-json\/wp\/v2\/bairro\/11364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/exames\/wp-json\/wp\/v2\/bairro"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/exames\/wp-json\/wp\/v2\/taxonomies\/bairro"}],"wp:post_type":[{"href":"https:\/\/www.somospopular.com.br\/exames\/wp-json\/wp\/v2\/negocio?bairro=11364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}