{"id":153966,"date":"2023-03-08T11:44:17","date_gmt":"2023-03-08T14:44:17","guid":{"rendered":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/"},"modified":"2023-03-08T11:44:17","modified_gmt":"2023-03-08T14:44:17","slug":"cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/","title":{"rendered":"Cobasi Hiper Barra Guanabara &#8211; Pet Shop na Barra da Tijuca &#8211; Rio de Janeiro &#8211; RJ"},"content":{"rendered":"<p>Cobasi iniciou suas atividades com a inaugura\u00e7\u00e3o da primeira unidade em 14 de outubro de 1985 , uma loja de produtos destinados \u00e0 atividade agropecu\u00e1ria e como pioneira a oferecer produtos para pequenos animais, numa \u00e9poca em que o mercado pet era pouco expressivo no Brasil.<\/p>\n<p>Atenta ao crescimento do mercado, a empresa maleavelmente se antecipou \u00e0s novas necessidades e conseguiu reestruturar sua linha de produtos e servi\u00e7os.<\/p>\n<p>A Cobasi foi pioneira a estabelecer o conceito de shopping para animais , de modo que o formato de suas lojas \u00e9 pioneiro e inovador.<\/p>\n<p>Hoje a Cobasi possui 58 lojas de varejo de auto-servi\u00e7o nas regi\u00f5es do Villa Lobos, Morumbi, Osasco, Brooklin, Imigrantes, Campinas \u2013 Galleria, Campinas &#8211; Cambu\u00ed, Butant\u00e3, Radial Leste, S\u00e3o Bernardo, Granja Vianna, Guarulhos, Interlar Interlagos, Barra da Tijuca \u2013 RJ, Marginal Pinheiros, S\u00e3o Jos\u00e9 dos Campos, Sorocaba, Ribeir\u00e3o Preto, Marginal Tiet\u00ea, S\u00e3o Caetano, Augusta, Guanabara &#8211; RJ, S\u00e3o Jose do Rio Preto, Teodoro, Praia Grande, Niter\u00f3i \u2013 RJ, Limeira, Araraquara, Atl\u00e2ntica, Campinas Taquaral, Atibaia, Piracicaba, Porto Alegre, Braz Leme, Aboli\u00e7\u00e3o Campinas, Embu das Artes, Rebou\u00e7as, Pomp\u00e9ia, Guarulhos &#8211; Tiradentes, Londrina Madre Le\u00f4nia, Bras\u00edlia Taquari, Londrina Centro, Interlagos, Bras\u00edlia CasaPark e Sena Madureira .<\/p>\n<p>A moderna estrutura permite aos clientes conforto e praticidade num s\u00f3 ambiente aconchegante, bonito, acolhedor e agrad\u00e1vel para propriet\u00e1rios e animais de estima\u00e7\u00e3o , de modo que as compras se tornam momentos de prazer. Portanto, os pets s\u00e3o muito bem vindos em nossas lojas, traga seu amigo para um passeio!<\/p>\n<p>E no conceito de lojas compactas segue com a marca Pet&#038;F\u00e1cil que atualmente se encontra nas regi\u00f5es de Washington Luis, Cerro Cor\u00e1, Carapicu\u00edba, Sabar\u00e1, Santo Andr\u00e9 e S\u00e3o Bernardo<\/p>\n<p>A empresa entende o quanto os animais de estima\u00e7\u00e3o s\u00e3o importantes, oferecendo companhia, amizade, conforto e alegria a seus donos. E os clientes contam com o entendimento desta estreita rela\u00e7\u00e3o que existe entre eles e seus bichinhos.<\/p>\n<p>Por este motivo a Cobasi deseja ser, a cada dia, a melhor organiza\u00e7\u00e3o dedicada \u00e0 cria\u00e7\u00e3o e ao enriquecimento do v\u00ednculo entre pessoas e animais. Seu compromisso consiste em suprir as necessidades dos clientes na venda de produtos, tudo em um s\u00f3 ambiente, bonito, acolhedor, agrad\u00e1vel e que estreite o m\u00e1ximo poss\u00edvel seu v\u00ednculo com a natureza.<\/p>\n<p>Cobasi &#8211; O shopping do seu animal.<\/p>\n<h3>Pet Shop na Barra da Tijuca &#8211; Rio de Janeiro &#8211; RJ<\/h3>\n<p><iframe loading=\"lazy\" title=\"Cobasi - O shopping do seu animal\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/UvW6oJJzW1A?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>Pet Shop\u00a0na Barra da Tijuca &#8211; Rio de Janeiro &#8211; RJ<\/p>\n<p><strong>Telefone:<\/strong> 11 3831-8999 | 21 2433-2538<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[6267],"categoria_parceiro":[6856],"topico-parceiro":[],"class_list":["post-153966","negocio","type-negocio","status-publish","hentry","bairro-barra-da-tijuca-rio-de-janeiro-rj","categoria_parceiro-pet-shop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ<\/title>\n<meta name=\"description\" content=\"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ. Veterin\u00e1rios na Barra da Tijuca - Rio de Janeiro - RJ\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cobasi Hiper Barra Guanabara - Pet Shop na Barra da Tijuca - Rio de Janeiro - RJ\" \/>\n<meta property=\"og:description\" content=\"Cobasi Hiper Barra Guanabara - Pet Shop na Barra da Tijuca - Rio de Janeiro - RJ. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\\\/\",\"name\":\"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\"},\"datePublished\":\"2023-03-08T14:44:17+00:00\",\"description\":\"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ. Veterin\u00e1rios na Barra da Tijuca - Rio de Janeiro - RJ\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veterin\u00e1rios\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cobasi Hiper Barra Guanabara &#8211; Pet Shop na Barra da Tijuca &#8211; Rio de Janeiro &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\",\"alternateName\":\"Cl\u00ednicas Veterin\u00e1ria\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ","description":"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ. Veterin\u00e1rios na Barra da Tijuca - Rio de Janeiro - RJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/","og_locale":"pt_BR","og_type":"article","og_title":"Cobasi Hiper Barra Guanabara - Pet Shop na Barra da Tijuca - Rio de Janeiro - RJ","og_description":"Cobasi Hiper Barra Guanabara - Pet Shop na Barra da Tijuca - Rio de Janeiro - RJ. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias","og_url":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/","og_site_name":"Cl\u00ednicas Veterin\u00e1rias","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/","name":"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website"},"datePublished":"2023-03-08T14:44:17+00:00","description":"Cobasi Hiper Barra Guanabara - Pet Shop\u00a0na Barra da Tijuca - Rio de Janeiro - RJ. Veterin\u00e1rios na Barra da Tijuca - Rio de Janeiro - RJ","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/cobasi-hiper-barra-guanabara-pet-shop-barra-da-tijuca-rio-de-janeiro-rj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veterin\u00e1rios","item":"https:\/\/www.somospopular.com.br\/veterinarios\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/veterinarios\/negocio\/"},{"@type":"ListItem","position":3,"name":"Cobasi Hiper Barra Guanabara &#8211; Pet Shop na Barra da Tijuca &#8211; Rio de Janeiro &#8211; RJ"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","name":"Cl\u00ednicas Veterin\u00e1rias","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/veterinarios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization","name":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular","alternateName":"Cl\u00ednicas Veterin\u00e1ria","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio\/153966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/media?parent=153966"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/bairro?post=153966"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/categoria_parceiro?post=153966"},{"taxonomy":"topico-parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/topico-parceiro?post=153966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}