{"id":158700,"date":"2021-01-04T19:40:34","date_gmt":"2021-01-04T22:40:34","guid":{"rendered":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/"},"modified":"2021-01-04T19:40:34","modified_gmt":"2021-01-04T22:40:34","slug":"casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/","title":{"rendered":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop &#8211; Veterin\u00e1rio em Governador Valadares"},"content":{"rendered":"<p>Onde Fica\u00a0Localiza\u00e7\u00e3o da empresas de Veterin\u00e1rio Centro\u00a0|\u00a0Veterin\u00e1rio em Governador Valadares\u00a0|\u00a0Veterin\u00e1rio em MG<\/p>\n<p><strong>Endere\u00e7o:<\/strong> RUA BELO HORIZONTE, 611 &#8211; CENTRO &#8211; GOVERNADOR VALADARES &#8211; MG CEP: 35010050<\/p>\n<p><strong>Telefone:<\/strong> (33) 3271-2172<\/p>\n<h2>Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop &#8211; Veterin\u00e1rio em Governador Valadares<\/h2>\n<p>Informa\u00e7\u00f5es sobre CASA DO FAZENDEIRO VETERIN\u00c1RIA E PET SHOP em Governador Valadares, Empresa de Veterinarios perto de Voc\u00ea! Endere\u00e7o, telefone, mapa e como chegar<\/p>\n<p><a href=\"https:\/\/maps.google.com\/maps\/dir\/\/R.+Belo+Horizonte,+611+-+Centro+Gov.+Valadares+-+MG+35010-050+Brazil\/@-18.8555013,-41.9479204,16z\/data=!4m5!4m4!1m0!1m2!1m1!1s0xb1a708f23e1fd7:0xd172a1dc87425ce4\">Como Chegar?<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[6420],"categoria_parceiro":[6760],"topico-parceiro":[13533],"class_list":["post-158700","negocio","type-negocio","status-publish","hentry","bairro-centro-governador-valadares-mg","categoria_parceiro-vacinacao-canina","topico-parceiro-vacinacao-canina-em-governador-valadares-mg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares<\/title>\n<meta name=\"description\" content=\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Governador Valadares\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares\" \/>\n<meta property=\"og:description\" content=\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\\\/\",\"name\":\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\"},\"datePublished\":\"2021-01-04T22:40:34+00:00\",\"description\":\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Governador Valadares\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veterin\u00e1rios\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vacina\u00e7\u00e3o Canina\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/vacinacao-canina\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop &#8211; Veterin\u00e1rio em Governador Valadares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\",\"alternateName\":\"Cl\u00ednicas Veterin\u00e1ria\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares","description":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Governador Valadares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/","og_locale":"pt_BR","og_type":"article","og_title":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares","og_description":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias","og_url":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/","og_site_name":"Cl\u00ednicas Veterin\u00e1rias","twitter_card":"summary_large_image","twitter_title":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/","name":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website"},"datePublished":"2021-01-04T22:40:34+00:00","description":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop - Veterin\u00e1rio em Governador Valadares. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Governador Valadares","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/casa-do-fazendeiro-veterinaria-e-pet-shop-veterinario-em-governador-valadares-mg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veterin\u00e1rios","item":"https:\/\/www.somospopular.com.br\/veterinarios\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/veterinarios\/negocio\/"},{"@type":"ListItem","position":3,"name":"Vacina\u00e7\u00e3o Canina","item":"https:\/\/www.somospopular.com.br\/veterinarios\/vacinacao-canina\/"},{"@type":"ListItem","position":4,"name":"Casa Do Fazendeiro Veterin\u00e1ria E Pet Shop &#8211; Veterin\u00e1rio em Governador Valadares"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","name":"Cl\u00ednicas Veterin\u00e1rias","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/veterinarios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization","name":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular","alternateName":"Cl\u00ednicas Veterin\u00e1ria","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio\/158700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/media?parent=158700"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/bairro?post=158700"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/categoria_parceiro?post=158700"},{"taxonomy":"topico-parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/topico-parceiro?post=158700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}