{"id":160159,"date":"2023-07-09T22:42:18","date_gmt":"2023-07-10T01:42:18","guid":{"rendered":"https:\/\/www.somospopular.com.br\/veterinarios\/?post_type=negocio&p=160159"},"modified":"2023-07-09T22:42:18","modified_gmt":"2023-07-10T01:42:18","slug":"agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/","title":{"rendered":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio &#8211; Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto"},"content":{"rendered":"<p>Onde Fica\u00a0Localiza\u00e7\u00e3o da empresas de Veterin\u00e1rio Jardim Manoel Del Arco\u00a0|\u00a0Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\u00a0|\u00a0Veterin\u00e1rio em SP<\/p>\n<p><strong>Endere\u00e7o:<\/strong> Rua Manoel Del Arco &#8211; s\/n &#8211; Jardim Manoel Del Arco, S\u00e3o Jos\u00e9 do Rio Preto &#8211; SP, 15046-708, Brasil<\/p>\n<p><strong>Telefone:<\/strong> (17) 3217-1737<\/p>\n<h2>Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio &#8211; Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto<\/h2>\n<p>Informa\u00e7\u00f5es sobre AGROCAV COM\u00c9RCIO DE PRODUTOS VETERIN\u00c1RIO em S\u00e3o Jos\u00e9 do Rio Preto, Empresa de Veterinarios perto de Voc\u00ea! Endere\u00e7o, telefone, mapa e como chegar<\/p>\n<p><a href=\"https:\/\/maps.google.com\/maps\/dir\/\/R.+Manoel+Del+Arco+-+Jardim+Manoel+Del+Arco+S%C3%A3o+Jos%C3%A9+do+Rio+Preto+-+SP+Brazil\/@-20.7678836,-49.3924292,16z\/data=!4m5!4m4!1m0!1m2!1m1!1s0x94bdaceea959de0b:0x171f7594e8410da8\">Como Chegar?<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[15425],"categoria_parceiro":[7073],"topico-parceiro":[15426],"class_list":["post-160159","negocio","type-negocio","status-publish","hentry","bairro-jardim-manoel-del-arco-sao-jose-do-rio-preto-sp","categoria_parceiro-arranhador-para-gatos","topico-parceiro-arranhador-para-gatos-em-sao-jose-do-rio-preto-sp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto<\/title>\n<meta name=\"description\" content=\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\" \/>\n<meta property=\"og:description\" content=\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\\\/\",\"name\":\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\"},\"datePublished\":\"2023-07-10T01:42:18+00:00\",\"description\":\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veterin\u00e1rios\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arranhador para Gatos\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/arranhador-para-gatos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio &#8211; Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\",\"alternateName\":\"Cl\u00ednicas Veterin\u00e1ria\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto","description":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto","og_description":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias","og_url":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/","og_site_name":"Cl\u00ednicas Veterin\u00e1rias","twitter_card":"summary_large_image","twitter_title":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/","name":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website"},"datePublished":"2023-07-10T01:42:18+00:00","description":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio - Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/agrocav-comercio-de-produtos-veterinario-veterinario-em-sao-jose-do-rio-preto-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veterin\u00e1rios","item":"https:\/\/www.somospopular.com.br\/veterinarios\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/veterinarios\/negocio\/"},{"@type":"ListItem","position":3,"name":"Arranhador para Gatos","item":"https:\/\/www.somospopular.com.br\/veterinarios\/arranhador-para-gatos\/"},{"@type":"ListItem","position":4,"name":"Agrocav Com\u00e9rcio de Produtos Veterin\u00e1rio &#8211; Veterin\u00e1rio em S\u00e3o Jos\u00e9 do Rio Preto"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","name":"Cl\u00ednicas Veterin\u00e1rias","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/veterinarios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization","name":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular","alternateName":"Cl\u00ednicas Veterin\u00e1ria","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio\/160159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/media?parent=160159"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/bairro?post=160159"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/categoria_parceiro?post=160159"},{"taxonomy":"topico-parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/topico-parceiro?post=160159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}