{"id":163096,"date":"2022-06-15T01:24:06","date_gmt":"2022-06-15T04:24:06","guid":{"rendered":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/"},"modified":"2022-06-15T01:24:06","modified_gmt":"2022-06-15T04:24:06","slug":"animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba","status":"publish","type":"negocio","link":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/","title":{"rendered":"Animalmede Cl\u00ednicas Veterin\u00e1ria &#8211; Veterin\u00e1rio em Juazeiro"},"content":{"rendered":"<p>Onde Fica\u00a0Localiza\u00e7\u00e3o da empresas de Veterin\u00e1rio \u00a0|\u00a0Veterin\u00e1rio em Juazeiro\u00a0|\u00a0Veterin\u00e1rio em BA<\/p>\n<p><strong>Endere\u00e7o:<\/strong> Avenida Flaviano Guimar\u00e3es, 1779 &#8211; Juazeiro &#8211; BA<\/p>\n<p><strong>Telefone:<\/strong> (74) 3611-4492<\/p>\n<h2>Animalmede Cl\u00ednicas Veterin\u00e1ria &#8211; Veterin\u00e1rio em Juazeiro<\/h2>\n<p>Informa\u00e7\u00f5es sobre ANIMALMEDE CL\u00cdNICAS VETERIN\u00c1RIA em Juazeiro, Empresa de Veterinarios perto de Voc\u00ea! Endere\u00e7o, telefone, mapa e como chegar<\/p>\n<p><a href=\"https:\/\/maps.google.com\/maps\/dir\/\/Av.+Flaviano+Guimar%C3%A3es,+1779+-+Cajueiro+Juazeiro+-+BA+48905-360+Brazil\/@-9.4183216,-40.4902734,16z\/data=!4m5!4m4!1m0!1m2!1m1!1s0x77371ca51783c7d:0x92e14250796fb089\">Como Chegar?<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","bairro":[11863],"categoria_parceiro":[6983],"topico-parceiro":[13732],"class_list":["post-163096","negocio","type-negocio","status-publish","hentry","bairro-centro-juazeiro-ba","categoria_parceiro-fisioterapia-veterinaria","topico-parceiro-fisioterapia-veterinaria-em-juazeiro-ba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro<\/title>\n<meta name=\"description\" content=\"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Juazeiro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro\" \/>\n<meta property=\"og:description\" content=\"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednicas Veterin\u00e1rias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\\\/\",\"name\":\"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\"},\"datePublished\":\"2022-06-15T04:24:06+00:00\",\"description\":\"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Juazeiro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veterin\u00e1rios\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceiros\",\"item\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Animalmede Cl\u00ednicas Veterin\u00e1ria &#8211; Veterin\u00e1rio em Juazeiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#website\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias\",\"description\":\"Somos Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#organization\",\"name\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\",\"alternateName\":\"Cl\u00ednicas Veterin\u00e1ria\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"contentUrl\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2022\\\/05\\\/somos-popular-logo-80.webp\",\"width\":325,\"height\":80,\"caption\":\"Cl\u00ednicas Veterin\u00e1rias - Somos Popular\"},\"image\":{\"@id\":\"https:\\\/\\\/www.somospopular.com.br\\\/veterinarios\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro","description":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Juazeiro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/","og_locale":"pt_BR","og_type":"article","og_title":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro","og_description":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro. Cl\u00ednica Veterin\u00e1ria Popular com pre\u00e7os acess\u00edveis. Cl\u00ednicas Veterin\u00e1rias","og_url":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/","og_site_name":"Cl\u00ednicas Veterin\u00e1rias","twitter_card":"summary_large_image","twitter_title":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/","name":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro","isPartOf":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website"},"datePublished":"2022-06-15T04:24:06+00:00","description":"Animalmede Cl\u00ednicas Veterin\u00e1ria - Veterin\u00e1rio em Juazeiro. Veterin\u00e1rios 24h perto de mim, Veterin\u00e1rio em Juazeiro","breadcrumb":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/animalmede-clinicas-veterinaria-veterinario-em-juazeiro-ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veterin\u00e1rios","item":"https:\/\/www.somospopular.com.br\/veterinarios\/"},{"@type":"ListItem","position":2,"name":"Parceiros","item":"https:\/\/www.somospopular.com.br\/veterinarios\/negocio\/"},{"@type":"ListItem","position":3,"name":"Animalmede Cl\u00ednicas Veterin\u00e1ria &#8211; Veterin\u00e1rio em Juazeiro"}]},{"@type":"WebSite","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#website","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","name":"Cl\u00ednicas Veterin\u00e1rias","description":"Somos Popular","publisher":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.somospopular.com.br\/veterinarios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#organization","name":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular","alternateName":"Cl\u00ednicas Veterin\u00e1ria","url":"https:\/\/www.somospopular.com.br\/veterinarios\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/","url":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","contentUrl":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-content\/uploads\/sites\/12\/2022\/05\/somos-popular-logo-80.webp","width":325,"height":80,"caption":"Cl\u00ednicas Veterin\u00e1rias - Somos Popular"},"image":{"@id":"https:\/\/www.somospopular.com.br\/veterinarios\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio\/163096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/negocio"}],"about":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/types\/negocio"}],"author":[{"embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/media?parent=163096"}],"wp:term":[{"taxonomy":"bairro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/bairro?post=163096"},{"taxonomy":"categoria_parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/categoria_parceiro?post=163096"},{"taxonomy":"topico-parceiro","embeddable":true,"href":"https:\/\/www.somospopular.com.br\/veterinarios\/wp-json\/wp\/v2\/topico-parceiro?post=163096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}